{"id":809913,"date":"2025-10-21T16:08:04","date_gmt":"2025-10-21T14:08:04","guid":{"rendered":"https:\/\/sbb-immobilien.ch\/immobilien\/1663011it-affitto-posteggi-esterni-centro-galleria-2-via-cantonale-manno\/"},"modified":"2026-09-01T15:48:42","modified_gmt":"2026-09-01T13:48:42","slug":"1663011it-affitto-posteggi-esterni-centro-galleria-2-via-cantonale-manno","status":"publish","type":"casawp_property","link":"https:\/\/sbb-immobilien.ch\/it\/immobili\/1663011it-affitto-posteggi-esterni-centro-galleria-2-via-cantonale-manno\/","title":{"rendered":"Affitto Posteggi Esterni \u2013 Centro Galleria 2, Via Cantonale, Manno"},"content":{"rendered":"<p>Affittiamo posteggi esterni presso il Centro Galleria 2, situato in Via Cantonale a Manno.<\/p>\n<p>La posizione strategica, nelle immediate vicinanze dell\u2019autostrada Lugano-Nord e in una zona commerciale, rende questi posteggi particolarmente adatti a professionisti, aziende e residenti che necessitano di un accesso comodo e veloce. <\/p>\n<p>Di fronte al Centro Galleria si trova la fermata del bus con collegamenti diretti verso il centro di Lugano.<\/p>\n<p>Tour informativo: Pamela Panizzolo Quaresima<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Affittiamo posteggi esterni presso il Centro Galleria 2, situato in Via Cantonale a Manno. La posizione strategica, nelle immediate vicinanze dell\u2019autostrada Lugano-Nord e in una zona commerciale, rende questi posteggi particolarmente adatti a professionisti, aziende e residenti che necessitano di un accesso comodo e veloce. Di fronte al Centro Galleria si trova la fermata del [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":809914,"parent":0,"menu_order":62,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"casawp_category":[15370],"casawp_feature":[],"casawp_utility":[15339],"casawp_location":[15308,15364,15363],"casawp_salestype":[15306],"casawp_availability":[15307],"casawp_region":[],"class_list":["post-809913","casawp_property","type-casawp_property","status-publish","has-post-thumbnail","hentry","casawp_category-open-slot","casawp_utility-parking","casawp_location-country_ch","casawp_location-locality_manno","casawp_location-region_ti","casawp_salestype-rent","casawp_availability-active"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Affitto Posteggi Esterni \u2013 Centro Galleria 2, Via Cantonale, Manno | FFS Immobili<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sbb-immobilien.ch\/it\/immobili\/1663011it-affitto-posteggi-esterni-centro-galleria-2-via-cantonale-manno\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Affitto Posteggi Esterni \u2013 Centro Galleria 2, Via Cantonale, Manno\" \/>\n<meta property=\"og:description\" content=\"Affittiamo posteggi esterni presso il Centro Galleria 2, situato in Via Cantonale a Manno. La posizione strategica, nelle immediate vicinanze dell\u2019autostrada Lugano-Nord e in una zona commerciale, rende questi posteggi particolarmente adatti a professionisti, aziende e residenti che necessitano di un accesso comodo e veloce. Di fronte al Centro Galleria si trova la fermata del [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sbb-immobilien.ch\/it\/immobili\/1663011it-affitto-posteggi-esterni-centro-galleria-2-via-cantonale-manno\/\" \/>\n<meta property=\"og:site_name\" content=\"FFS Immobili\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-01T13:48:42+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"RealEstateListing\"],\"@id\":\"https:\\\/\\\/sbb-immobilien.ch\\\/it\\\/immobili\\\/1663011it-affitto-posteggi-esterni-centro-galleria-2-via-cantonale-manno\\\/\",\"url\":\"https:\\\/\\\/sbb-immobilien.ch\\\/it\\\/immobili\\\/1663011it-affitto-posteggi-esterni-centro-galleria-2-via-cantonale-manno\\\/\",\"name\":\"Affitto Posteggi Esterni \u2013 Centro Galleria 2, Via Cantonale, Manno | FFS Immobili\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sbb-immobilien.ch\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sbb-immobilien.ch\\\/it\\\/immobili\\\/1663011it-affitto-posteggi-esterni-centro-galleria-2-via-cantonale-manno\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sbb-immobilien.ch\\\/it\\\/immobili\\\/1663011it-affitto-posteggi-esterni-centro-galleria-2-via-cantonale-manno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.casasoft.com\\\/media\\\/provider-13858\\\/property-1663011\\\/advertisement-language-7160b522-84ae-f011-bbd3-6045bd2a418a-IMG_9204.JPEG?p=xl\",\"datePublished\":\"2025-10-21T14:08:04+00:00\",\"dateModified\":\"2026-09-01T13:48:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sbb-immobilien.ch\\\/it\\\/immobili\\\/1663011it-affitto-posteggi-esterni-centro-galleria-2-via-cantonale-manno\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sbb-immobilien.ch\\\/it\\\/immobili\\\/1663011it-affitto-posteggi-esterni-centro-galleria-2-via-cantonale-manno\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/sbb-immobilien.ch\\\/it\\\/immobili\\\/1663011it-affitto-posteggi-esterni-centro-galleria-2-via-cantonale-manno\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.casasoft.com\\\/media\\\/provider-13858\\\/property-1663011\\\/advertisement-language-7160b522-84ae-f011-bbd3-6045bd2a418a-IMG_9204.JPEG?p=xl\",\"contentUrl\":\"https:\\\/\\\/cdn.casasoft.com\\\/media\\\/provider-13858\\\/property-1663011\\\/advertisement-language-7160b522-84ae-f011-bbd3-6045bd2a418a-IMG_9204.JPEG?p=xl\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sbb-immobilien.ch\\\/it\\\/immobili\\\/1663011it-affitto-posteggi-esterni-centro-galleria-2-via-cantonale-manno\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sbb-immobilien.ch\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Propriet\u00e0\",\"item\":\"https:\\\/\\\/sbb-immobilien.ch\\\/it\\\/immobili\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Affitto Posteggi Esterni \u2013 Centro Galleria 2, Via Cantonale, Manno\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sbb-immobilien.ch\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/sbb-immobilien.ch\\\/it\\\/\",\"name\":\"FFS Immobili\",\"description\":\"Immobili nella migliore posizione.\",\"publisher\":{\"@id\":\"https:\\\/\\\/sbb-immobilien.ch\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sbb-immobilien.ch\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sbb-immobilien.ch\\\/it\\\/#organization\",\"name\":\"SBB Immobilien\",\"url\":\"https:\\\/\\\/sbb-immobilien.ch\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/sbb-immobilien.ch\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\/\\/cdn.sbb-immobilien.ch\\/w:1617\\/h:1080\\/q:mauto\\/f:best\\/https:\\/\\/sbb-immobilien.ch\\/wp-content\\/uploads\\/2021\\/11\\/SBB_byte_200329_DSC_4292_2500px.jpg\",\"contentUrl\":\"https:\\/\\/cdn.sbb-immobilien.ch\\/w:1617\\/h:1080\\/q:mauto\\/f:best\\/https:\\/\\/sbb-immobilien.ch\\/wp-content\\/uploads\\/2021\\/11\\/SBB_byte_200329_DSC_4292_2500px.jpg\",\"width\":2500,\"height\":1669,\"caption\":\"SBB Immobilien\"},\"image\":{\"@id\":\"https:\\\/\\\/sbb-immobilien.ch\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/ch.linkedin.com\\\/showcase\\\/immobilienberufe?trk=affiliated-pages\",\"https:\\\/\\\/de.wikipedia.org\\\/wiki\\\/Schweizerische_Bundesbahnen\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Affitto Posteggi Esterni \u2013 Centro Galleria 2, Via Cantonale, Manno | FFS Immobili","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sbb-immobilien.ch\/it\/immobili\/1663011it-affitto-posteggi-esterni-centro-galleria-2-via-cantonale-manno\/","og_locale":"it_IT","og_type":"article","og_title":"Affitto Posteggi Esterni \u2013 Centro Galleria 2, Via Cantonale, Manno","og_description":"Affittiamo posteggi esterni presso il Centro Galleria 2, situato in Via Cantonale a Manno. La posizione strategica, nelle immediate vicinanze dell\u2019autostrada Lugano-Nord e in una zona commerciale, rende questi posteggi particolarmente adatti a professionisti, aziende e residenti che necessitano di un accesso comodo e veloce. Di fronte al Centro Galleria si trova la fermata del [&hellip;]","og_url":"https:\/\/sbb-immobilien.ch\/it\/immobili\/1663011it-affitto-posteggi-esterni-centro-galleria-2-via-cantonale-manno\/","og_site_name":"FFS Immobili","article_modified_time":"2026-09-01T13:48:42+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","RealEstateListing"],"@id":"https:\/\/sbb-immobilien.ch\/it\/immobili\/1663011it-affitto-posteggi-esterni-centro-galleria-2-via-cantonale-manno\/","url":"https:\/\/sbb-immobilien.ch\/it\/immobili\/1663011it-affitto-posteggi-esterni-centro-galleria-2-via-cantonale-manno\/","name":"Affitto Posteggi Esterni \u2013 Centro Galleria 2, Via Cantonale, Manno | FFS Immobili","isPartOf":{"@id":"https:\/\/sbb-immobilien.ch\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sbb-immobilien.ch\/it\/immobili\/1663011it-affitto-posteggi-esterni-centro-galleria-2-via-cantonale-manno\/#primaryimage"},"image":{"@id":"https:\/\/sbb-immobilien.ch\/it\/immobili\/1663011it-affitto-posteggi-esterni-centro-galleria-2-via-cantonale-manno\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.casasoft.com\/media\/provider-13858\/property-1663011\/advertisement-language-7160b522-84ae-f011-bbd3-6045bd2a418a-IMG_9204.JPEG?p=xl","datePublished":"2025-10-21T14:08:04+00:00","dateModified":"2026-09-01T13:48:42+00:00","breadcrumb":{"@id":"https:\/\/sbb-immobilien.ch\/it\/immobili\/1663011it-affitto-posteggi-esterni-centro-galleria-2-via-cantonale-manno\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sbb-immobilien.ch\/it\/immobili\/1663011it-affitto-posteggi-esterni-centro-galleria-2-via-cantonale-manno\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/sbb-immobilien.ch\/it\/immobili\/1663011it-affitto-posteggi-esterni-centro-galleria-2-via-cantonale-manno\/#primaryimage","url":"https:\/\/cdn.casasoft.com\/media\/provider-13858\/property-1663011\/advertisement-language-7160b522-84ae-f011-bbd3-6045bd2a418a-IMG_9204.JPEG?p=xl","contentUrl":"https:\/\/cdn.casasoft.com\/media\/provider-13858\/property-1663011\/advertisement-language-7160b522-84ae-f011-bbd3-6045bd2a418a-IMG_9204.JPEG?p=xl"},{"@type":"BreadcrumbList","@id":"https:\/\/sbb-immobilien.ch\/it\/immobili\/1663011it-affitto-posteggi-esterni-centro-galleria-2-via-cantonale-manno\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sbb-immobilien.ch\/it\/"},{"@type":"ListItem","position":2,"name":"Propriet\u00e0","item":"https:\/\/sbb-immobilien.ch\/it\/immobili\/"},{"@type":"ListItem","position":3,"name":"Affitto Posteggi Esterni \u2013 Centro Galleria 2, Via Cantonale, Manno"}]},{"@type":"WebSite","@id":"https:\/\/sbb-immobilien.ch\/it\/#website","url":"https:\/\/sbb-immobilien.ch\/it\/","name":"FFS Immobili","description":"Immobili nella migliore posizione.","publisher":{"@id":"https:\/\/sbb-immobilien.ch\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sbb-immobilien.ch\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/sbb-immobilien.ch\/it\/#organization","name":"SBB Immobilien","url":"https:\/\/sbb-immobilien.ch\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/sbb-immobilien.ch\/it\/#\/schema\/logo\/image\/","url":"https:\/\/cdn.sbb-immobilien.ch\/w:1617\/h:1080\/q:mauto\/f:best\/https:\/\/sbb-immobilien.ch\/wp-content\/uploads\/2021\/11\/SBB_byte_200329_DSC_4292_2500px.jpg","contentUrl":"https:\/\/cdn.sbb-immobilien.ch\/w:1617\/h:1080\/q:mauto\/f:best\/https:\/\/sbb-immobilien.ch\/wp-content\/uploads\/2021\/11\/SBB_byte_200329_DSC_4292_2500px.jpg","width":2500,"height":1669,"caption":"SBB Immobilien"},"image":{"@id":"https:\/\/sbb-immobilien.ch\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/ch.linkedin.com\/showcase\/immobilienberufe?trk=affiliated-pages","https:\/\/de.wikipedia.org\/wiki\/Schweizerische_Bundesbahnen"]}]}},"_links":{"self":[{"href":"https:\/\/sbb-immobilien.ch\/it\/wp-json\/wp\/v2\/casawp_property\/809913","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sbb-immobilien.ch\/it\/wp-json\/wp\/v2\/casawp_property"}],"about":[{"href":"https:\/\/sbb-immobilien.ch\/it\/wp-json\/wp\/v2\/types\/casawp_property"}],"replies":[{"embeddable":true,"href":"https:\/\/sbb-immobilien.ch\/it\/wp-json\/wp\/v2\/comments?post=809913"}],"version-history":[{"count":1,"href":"https:\/\/sbb-immobilien.ch\/it\/wp-json\/wp\/v2\/casawp_property\/809913\/revisions"}],"predecessor-version":[{"id":818418,"href":"https:\/\/sbb-immobilien.ch\/it\/wp-json\/wp\/v2\/casawp_property\/809913\/revisions\/818418"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sbb-immobilien.ch\/it\/wp-json\/wp\/v2\/media\/809914"}],"wp:attachment":[{"href":"https:\/\/sbb-immobilien.ch\/it\/wp-json\/wp\/v2\/media?parent=809913"}],"wp:term":[{"taxonomy":"casawp_category","embeddable":true,"href":"https:\/\/sbb-immobilien.ch\/it\/wp-json\/wp\/v2\/casawp_category?post=809913"},{"taxonomy":"casawp_feature","embeddable":true,"href":"https:\/\/sbb-immobilien.ch\/it\/wp-json\/wp\/v2\/casawp_feature?post=809913"},{"taxonomy":"casawp_utility","embeddable":true,"href":"https:\/\/sbb-immobilien.ch\/it\/wp-json\/wp\/v2\/casawp_utility?post=809913"},{"taxonomy":"casawp_location","embeddable":true,"href":"https:\/\/sbb-immobilien.ch\/it\/wp-json\/wp\/v2\/casawp_location?post=809913"},{"taxonomy":"casawp_salestype","embeddable":true,"href":"https:\/\/sbb-immobilien.ch\/it\/wp-json\/wp\/v2\/casawp_salestype?post=809913"},{"taxonomy":"casawp_availability","embeddable":true,"href":"https:\/\/sbb-immobilien.ch\/it\/wp-json\/wp\/v2\/casawp_availability?post=809913"},{"taxonomy":"casawp_region","embeddable":true,"href":"https:\/\/sbb-immobilien.ch\/it\/wp-json\/wp\/v2\/casawp_region?post=809913"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}